{"id":1415,"date":"2021-09-21T18:18:28","date_gmt":"2021-09-21T23:18:28","guid":{"rendered":"https:\/\/singularityumexicosummit.com\/?p=1415"},"modified":"2021-09-21T18:18:28","modified_gmt":"2021-09-21T23:18:28","slug":"la-inteligencia-artificial-como-herramienta-contra-el-parkinson","status":"publish","type":"post","link":"https:\/\/singularityumexico.com\/en\/la-inteligencia-artificial-como-herramienta-contra-el-parkinson\/","title":{"rendered":"La inteligencia Artificial como herramienta contra el Parkinson"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Lo m\u00e1s probable es que sepas que el actor Michael J. Fox vive con la enfermedad de Parkinson. En el a\u00f1o 2000, Fox lanz\u00f3 su propia fundaci\u00f3n para la Investigaci\u00f3n del Parkinson (MJFF) con la intenci\u00f3n de buscar tratamientos y una cura para esta condici\u00f3n que afecta a un estimado de m\u00e1s de seis millones de personas en todo el mundo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde entonces, el equipo interno de neurocient\u00edficos y estrategas comerciales de MJFF ha estado trabajando de la mano con investigadores de ciencia y tecnolog\u00eda, m\u00e9dicos, socios de la industria y pacientes de todo el mundo para desarrollar algunas de las investigaciones m\u00e1s prometedoras para la comprensi\u00f3n y el mejor tratamiento de la enfermedad.En julio de 2018, se concret\u00f3 una alianza sin precedentes con IBM Research para aplicar herramientas de machine learning y concretar avances cient\u00edficos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recientemente, esta colaboraci\u00f3n ha alcanzado un hito significativo. En su \u00faltimo trabajo nombrado:\u00a0\u00a0\u201cDescubrimiento de los estados de la enfermedad de Parkinson mediante machine learning y datos longitudinales\u201d. Se detalla un nuevo modelo de Inteligencia Artificial que agrupa los patrones de s\u00edntomas t\u00edpicos de la enfermedad de Parkinson. El modelo ha sido tan exitoso que ha logrado predecir la progresi\u00f3n de estos s\u00edntomas y su gravedad, al aprender de lo que se conoce como datos longitudinales del paciente: un conjunto de datos del paciente compuestos por el estado cl\u00ednico de un paciente y que son recopilados a lo largo del tiempo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"949\" height=\"540\" src=\"https:\/\/singularityumexicosummit.com\/wp-content\/uploads\/2021\/09\/2-4.jpg\" alt=\"\" class=\"wp-image-1417\" srcset=\"https:\/\/singularityumexico.com\/wp-content\/uploads\/2021\/09\/2-4.jpg 949w, https:\/\/singularityumexico.com\/wp-content\/uploads\/2021\/09\/2-4-300x171.jpg 300w, https:\/\/singularityumexico.com\/wp-content\/uploads\/2021\/09\/2-4-768x437.jpg 768w, https:\/\/singularityumexico.com\/wp-content\/uploads\/2021\/09\/2-4-18x10.jpg 18w\" sizes=\"(max-width: 949px) 100vw, 949px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Tener acceso a un gran conjunto de datos es crucial para el \u00e9xito en los modelos de machine learning, para el caso de la Fundaci\u00f3n Michael J. Fox, los estudios se basaron en hasta 7 a\u00f1os de datos de pacientes, un c\u00famulo de informaci\u00f3n impresionante que permiti\u00f3 el descubrimiento de patrones de progresi\u00f3n y s\u00edntomas complejos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Debido a la diversidad de casos, experiencias, y factores que podr\u00edan hacer un diferenciador en cada persona con la enfermedad de Parkinson, se espera que al permitir tales predicciones, el modelo pueda ayudar en el manejo del paciente y proporcionar criterios de que unifiquen la direcci\u00f3n de la enfermedad y definir tratamientos espec\u00edficos y con un mayor grado de certeza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A\u00fan hay camino por recorrer, sin embargo, este es solo un ejemplo de c\u00f3mo al canalizar las ideas y apoyarlas con tecnolog\u00eda, investigaci\u00f3n e innovaci\u00f3n, podemos ayudar a conseguir un impacto importante en la vida de personas en todo el mundo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conoce m\u00e1s acerca del futuro de la salud en\u00a0<a href=\"https:\/\/singularityumexicosummit.com\/#Boletos\" target=\"_blank\" rel=\"noreferrer noopener\">SingularityUMx Digital Series Jalisco 2021<\/a>, un evento con informaci\u00f3n de valor a cargo de expertos internacionales que brindar\u00e1n su conocimiento para expandir las fronteras de nuestra visi\u00f3n, nuestro futuro y nuestro bienestar.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" src=\"https:\/\/singularityumexicosummit.com\/wp-content\/uploads\/2021\/08\/Captura-de-Pantalla-2021-08-31-a-las-15.44.12.png\" alt=\"Separador\" class=\"wp-image-1036\"\/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fuentes:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">IBM and The Michael J. Fox Foundation use AI to help predict progression of Parkinson\u2019s disease<br><strong>Autores:<\/strong> Kristen Severson, Soumyadip Ghosh, Jianying Hu<\/p>","protected":false},"excerpt":{"rendered":"<p>Un nuevo hito en el tratamiento de esta enfermedad<\/p>","protected":false},"author":1,"featured_media":1416,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","footnotes":""},"categories":[25],"tags":[],"series":[],"class_list":["post-1415","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos-espanol"],"episode_featured_image":"https:\/\/singularityumexico.com\/wp-content\/uploads\/2021\/09\/1-copia-3.jpg","episode_player_image":"https:\/\/singularityumexico.com\/wp-content\/uploads\/2023\/05\/11711533-1673157178559-89a95be153719-4-scaled.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/singularityumexico.com\/en\/feed\/podcast\/the-feedback-loop-by-singularity","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"QLt1mHpLqJ\"><a href=\"https:\/\/singularityumexico.com\/en\/la-inteligencia-artificial-como-herramienta-contra-el-parkinson\/\">La inteligencia Artificial como herramienta contra el Parkinson<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/singularityumexico.com\/en\/la-inteligencia-artificial-como-herramienta-contra-el-parkinson\/embed\/#?secret=QLt1mHpLqJ\" width=\"500\" height=\"350\" title=\"&#8220;La inteligencia Artificial como herramienta contra el Parkinson&#8221; &#8212; Singularity Mexico\" data-secret=\"QLt1mHpLqJ\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/singularityumexico.com\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/singularityumexico.com\/en\/wp-json\/wp\/v2\/posts\/1415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/singularityumexico.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/singularityumexico.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/singularityumexico.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/singularityumexico.com\/en\/wp-json\/wp\/v2\/comments?post=1415"}],"version-history":[{"count":0,"href":"https:\/\/singularityumexico.com\/en\/wp-json\/wp\/v2\/posts\/1415\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/singularityumexico.com\/en\/wp-json\/wp\/v2\/media\/1416"}],"wp:attachment":[{"href":"https:\/\/singularityumexico.com\/en\/wp-json\/wp\/v2\/media?parent=1415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/singularityumexico.com\/en\/wp-json\/wp\/v2\/categories?post=1415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/singularityumexico.com\/en\/wp-json\/wp\/v2\/tags?post=1415"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/singularityumexico.com\/en\/wp-json\/wp\/v2\/series?post=1415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}